{"id":2867,"date":"2020-07-25T23:33:33","date_gmt":"2020-07-25T23:33:33","guid":{"rendered":"https:\/\/winandofficews.com\/?page_id=2867"},"modified":"2025-08-25T20:36:01","modified_gmt":"2025-08-25T18:36:01","slug":"datenschutzerklaerung","status":"publish","type":"page","link":"https:\/\/winandofficews.com\/it\/datenschutzerklaerung\/","title":{"rendered":"Normativa sulla protezione dei dati"},"content":{"rendered":"<h2><\/h2>\n<section data-id=\"0042652\" data-element_type=\"section\">\n<h2>1. La protezione dei dati in sintesi<\/h2>\n<h3>Informazioni generali<\/h3>\n<p>Le seguenti informazioni forniscono una semplice panoramica di ci\u00f2 che accade ai vostri dati personali quando visitate questo sito web. Per dati personali si intendono tutti i dati che possono essere utilizzati per identificarvi personalmente. Informazioni dettagliate sul tema della protezione dei dati sono disponibili nella nostra dichiarazione sulla protezione dei dati riportata sotto questo testo.<\/p>\n<h3>Raccolta di dati su questo sito web<\/h3>\n<p><strong>Chi \u00e8 responsabile della raccolta dei dati su questo sito?<\/strong><\/p>\n<p>Il trattamento dei dati su questo sito web viene effettuato dal gestore del sito. I dati di contatto del gestore sono riportati nelle note legali di questo sito.<\/p>\n<p><strong>Come raccogliamo i vostri dati?<\/strong><\/p>\n<p>Da un lato, i vostri dati vengono raccolti quando ce li fornite. Pu\u00f2 trattarsi, ad esempio, dei dati inseriti in un modulo di contatto.<\/p>\n<p>Altri dati vengono raccolti automaticamente o con il vostro consenso dai nostri sistemi informatici quando visitate il sito web. Si tratta principalmente di dati tecnici (ad es. browser Internet, sistema operativo o tempo di visualizzazione della pagina). Questi dati vengono raccolti automaticamente non appena si accede al sito web.<\/p>\n<p><strong>Per cosa utilizziamo i vostri dati?<\/strong><\/p>\n<p>Alcuni dati vengono raccolti per garantire che il sito web venga fornito senza errori. Altri dati possono essere utilizzati per analizzare il comportamento degli utenti.<\/p>\n<p><strong>Quali diritti avete sui vostri dati?<\/strong><\/p>\n<p>Avete il diritto di ricevere gratuitamente in qualsiasi momento informazioni sull'origine, il destinatario e lo scopo dei vostri dati personali memorizzati. Avete inoltre il diritto di richiedere la correzione o la cancellazione di tali dati. Se avete dato il vostro consenso al trattamento dei dati, potete revocarlo in qualsiasi momento per il futuro. Avete anche il diritto di richiedere la limitazione del trattamento dei vostri dati personali in determinate circostanze. Inoltre, avete il diritto di presentare un reclamo all'autorit\u00e0 di vigilanza competente.<\/p>\n<p>Per ulteriori domande sul tema della protezione dei dati, potete contattarci in qualsiasi momento all'indirizzo indicato nella nota legale.<\/p>\n<h3>Strumenti di analisi e strumenti di fornitori terzi<\/h3>\n<p>Quando visitate questo sito web, il vostro comportamento di navigazione pu\u00f2 essere valutato statisticamente. Ci\u00f2 avviene principalmente attraverso i cookie e i cosiddetti programmi di analisi.<\/p>\n<p>Informazioni dettagliate su questi programmi di analisi sono disponibili nella seguente informativa sulla privacy.<\/p>\n<h2>2. hosting e reti di distribuzione dei contenuti (CDN)<\/h2>\n<h3>Hosting esterno<\/h3>\n<p>Questo sito web \u00e8 ospitato da un fornitore di servizi esterno (hoster). I dati personali raccolti su questo sito web sono memorizzati sui server dell'hoster. Tali dati possono includere indirizzi IP, richieste di contatto, dati meta e di comunicazione, dati contrattuali, dettagli di contatto, nomi, accessi al sito web e altri dati generati tramite un sito web.<\/p>\n<p>L'hoster viene utilizzato ai fini dell'adempimento del contratto con i nostri clienti potenziali ed esistenti (art. 6 par. 1 lett. b GDPR) e nell'interesse di una fornitura sicura, veloce ed efficiente della nostra offerta online da parte di un fornitore professionale (art. 6 par. 1 lett. f GDPR).<\/p>\n<p>Il nostro hoster tratter\u00e0 i vostri dati solo nella misura necessaria per adempiere ai suoi obblighi di prestazione e seguire le nostre istruzioni in merito a tali dati.<\/p>\n<p><strong>Conclusione di un contratto per l'elaborazione degli ordini<\/strong><\/p>\n<p>Per garantire un trattamento dei dati conforme alla protezione dei dati, abbiamo stipulato un contratto di elaborazione degli ordini con il nostro hoster.<\/p>\n<h2>3 Note generali e informazioni obbligatorie<\/h2>\n<h3>Protezione dei dati<\/h3>\n<p>I gestori di queste pagine prendono molto sul serio la protezione dei vostri dati personali. Trattiamo i vostri dati personali in modo confidenziale e in conformit\u00e0 alle norme di legge sulla protezione dei dati e alla presente informativa sulla privacy.<\/p>\n<p>Quando si utilizza questo sito web, vengono raccolti diversi dati personali. I dati personali sono dati che possono essere utilizzati per identificarvi personalmente. La presente informativa sulla privacy spiega quali dati raccogliamo e per quali scopi li utilizziamo. Spiega inoltre come e per quale scopo vengono raccolti.<\/p>\n<p>Desideriamo sottolineare che la trasmissione dei dati su Internet (ad esempio, quando si comunica via e-mail) pu\u00f2 essere soggetta a vulnerabilit\u00e0 di sicurezza. Non \u00e8 possibile proteggere completamente i dati dall'accesso di terzi.<\/p>\n<h3>Nota sull'organismo responsabile<\/h3>\n<p>Il responsabile del trattamento dei dati su questo sito web \u00e8<\/p>\n<div class=\"entry-content\">\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Proprietario:<\/strong> INES CASTRO ANDIA<\/p>\n<p><strong>Sede centrale: <\/strong>Samoastrasse 1, 13353 Berlino, Germania<\/p>\n<p><strong>Posizione Germania: <\/strong>Samoastrasse 1, 13353 Berlino, Germania<br \/>\n<strong>Tel:<\/strong> +49 60213274874<br \/>\n<strong>e-mail:<\/strong> <a href=\"mailto:&lt;a href=&#039;mailto:contact@winandofficews.com&#039;&gt;contact@winandofficews.com&lt;\/a&gt;\"><a href='mailto:contact@winandofficews.com'>contact@winandofficews.com<\/a><\/a><\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<p>Il responsabile del trattamento \u00e8 la persona fisica o giuridica che, da sola o insieme ad altri, determina le finalit\u00e0 e i mezzi del trattamento dei dati personali (ad esempio, nomi, indirizzi e-mail, ecc.).<\/p>\n<h3>Revoca del consenso al trattamento dei dati<\/h3>\n<p>Molte operazioni di trattamento dei dati sono possibili solo con il vostro consenso esplicito. Potete revocare in qualsiasi momento il consenso che avete gi\u00e0 dato. Tutto ci\u00f2 che dovete fare \u00e8 inviarci un'e-mail informale. La legalit\u00e0 del trattamento dei dati effettuato fino alla revoca rimane inalterata.<\/p>\n<h3>Diritto di opporsi alla raccolta dei dati in casi particolari e al marketing diretto (Art. 21 GDPR)<\/h3>\n<p>SE IL TRATTAMENTO DEI DATI SI BASA SULL'ART. 6 ABS. 1 LIT. E O F DEL GDPR, AVETE IL DIRITTO DI OPPORVI IN QUALSIASI MOMENTO AL TRATTAMENTO DEI VOSTRI DATI PERSONALI PER MOTIVI CONNESSI ALLA VOSTRA SITUAZIONE PARTICOLARE; CI\u00d2 VALE ANCHE PER LA PROFILAZIONE BASATA SU TALI DISPOSIZIONI. LE RISPETTIVE BASI GIURIDICHE SU CUI SI FONDA IL TRATTAMENTO SONO RIPORTATE NELLA PRESENTE INFORMATIVA SULLA PRIVACY. IN CASO DI OPPOSIZIONE, NON TRATTEREMO PI\u00d9 I VOSTRI DATI PERSONALI IN QUESTIONE, A MENO CHE NON POSSIAMO DIMOSTRARE MOTIVI LEGITTIMI IMPELLENTI PER IL TRATTAMENTO CHE PREVALGONO SUI VOSTRI INTERESSI, DIRITTI E LIBERT\u00c0 O CHE IL TRATTAMENTO SERVE PER L'ISTITUZIONE, L'ESERCIZIO O LA DIFESA DI RIVENDICAZIONI LEGALI (OBIEZIONE AI SENSI DELL'ART. 21 PAR. 1 GDPR).<\/p>\n<p>SE I VOSTRI DATI PERSONALI SONO TRATTATI PER FINALIT\u00c0 DI MARKETING DIRETTO, AVETE IL DIRITTO DI OPPORVI IN QUALSIASI MOMENTO AL TRATTAMENTO DEI DATI PERSONALI CHE VI RIGUARDANO PER TALI FINALIT\u00c0; CI\u00d2 VALE ANCHE PER LA PROFILAZIONE NELLA MISURA IN CUI \u00c8 CONNESSA A TALE MARKETING DIRETTO. IN CASO DI OPPOSIZIONE, I VOSTRI DATI PERSONALI NON SARANNO PI\u00d9 UTILIZZATI PER FINALIT\u00c0 DI MARKETING DIRETTO (OPPOSIZIONE AI SENSI DELL'ART. 21 PAR. 2 GDPR).<\/p>\n<h3>Diritto di presentare un reclamo all'autorit\u00e0 di controllo competente<\/h3>\n<p>In caso di violazione del GDPR, gli interessati hanno il diritto di proporre reclamo a un'autorit\u00e0 di controllo, in particolare nello Stato membro in cui risiedono abitualmente, lavorano o in cui si \u00e8 verificata la presunta violazione. Il diritto di presentare un reclamo non pregiudica eventuali altri rimedi amministrativi o giudiziari.<\/p>\n<h3>Diritto alla portabilit\u00e0 dei dati<\/h3>\n<p>Avete il diritto di ottenere che i dati da noi trattati automaticamente sulla base del vostro consenso o in adempimento di un contratto vengano consegnati a voi o a terzi in un formato comunemente utilizzato e leggibile da una macchina. Se richiedete il trasferimento diretto dei dati a un altro responsabile del trattamento, ci\u00f2 avverr\u00e0 solo nella misura in cui ci\u00f2 sia tecnicamente possibile.<\/p>\n<h3>Crittografia SSL o TLS<\/h3>\n<p>Questo sito utilizza la crittografia SSL o TLS per motivi di sicurezza e per proteggere la trasmissione di contenuti riservati, come gli ordini o le richieste di informazioni che ci inviate in qualit\u00e0 di gestore del sito. \u00c8 possibile riconoscere una connessione crittografata dal fatto che la riga dell'indirizzo del browser passa da \u201ehttp:\/\/\u201c a \u201ehttps:\/\/\u201c e dal simbolo del lucchetto nella riga del browser.<\/p>\n<p>Se la crittografia SSL o TLS \u00e8 attivata, i dati che ci trasmettete non possono essere letti da terzi.<\/p>\n<h3>Transazioni di pagamento criptate su questo sito web<\/h3>\n<p>Se esiste l'obbligo di fornirci i dati di pagamento (ad esempio il numero di conto per l'autorizzazione all'addebito diretto) dopo la conclusione di un contratto a pagamento, tali dati sono necessari per l'elaborazione del pagamento.<\/p>\n<p>Le transazioni di pagamento tramite i consueti mezzi di pagamento (Visa\/MasterCard, addebito diretto) avvengono esclusivamente tramite una connessione criptata SSL o TLS. Una connessione criptata si riconosce dal fatto che la riga dell'indirizzo del browser passa da \u201ehttp:\/\/\u201c a \u201ehttps:\/\/\u201c e dal simbolo del lucchetto nella riga del browser.<\/p>\n<p>Con la comunicazione criptata, i dati di pagamento che ci trasmettete non possono essere letti da terzi.<\/p>\n<h3>Informazioni, cancellazione e correzione<\/h3>\n<p>Nell'ambito delle disposizioni di legge applicabili, avete il diritto di ottenere in qualsiasi momento informazioni gratuite sui vostri dati personali memorizzati, sulla loro origine e sul loro destinatario e sullo scopo del trattamento dei dati e, se necessario, il diritto alla correzione o alla cancellazione di tali dati. Per ulteriori domande sul tema dei dati personali, potete contattarci in qualsiasi momento all'indirizzo indicato nella nota legale.<\/p>\n<h3>Diritto alla limitazione del trattamento<\/h3>\n<p>Avete il diritto di richiedere la limitazione del trattamento dei vostri dati personali. A tal fine, potete contattarci in qualsiasi momento all'indirizzo indicato nella nota legale. Il diritto alla limitazione del trattamento sussiste nei seguenti casi:<\/p>\n<ul>\n<li>Se contestate l'esattezza dei vostri dati personali da noi memorizzati, in genere abbiamo bisogno di tempo per verificarla. Per la durata della verifica, avete il diritto di chiedere che il trattamento dei vostri dati personali sia limitato.<\/li>\n<li>Se il trattamento dei vostri dati personali era\/\u00e8 illegale, potete richiedere la limitazione del trattamento dei dati invece della cancellazione.<\/li>\n<li>Se non abbiamo pi\u00f9 bisogno dei vostri dati personali, ma vi servono per l'esercizio, la difesa o l'affermazione di diritti legali, avete il diritto di richiedere la limitazione del trattamento dei vostri dati personali invece della loro cancellazione.<\/li>\n<li>Se avete presentato un'obiezione ai sensi dell'art. 21 (1) GDPR, \u00e8 necessario trovare un equilibrio tra i vostri interessi e i nostri. Finch\u00e9 non \u00e8 ancora stato stabilito quali interessi prevalgono, avete il diritto di chiedere la limitazione del trattamento dei vostri dati personali.<\/li>\n<\/ul>\n<p>Se avete limitato il trattamento dei vostri dati personali, questi - a parte la loro conservazione - potranno essere trattati solo con il vostro consenso o per l'accertamento, l'esercizio o la difesa di diritti legali o per la tutela dei diritti di un'altra persona fisica o giuridica o per motivi di rilevante interesse pubblico dell'Unione europea o di uno Stato membro.<\/p>\n<h3>Obiezione alle e-mail pubblicitarie<\/h3>\n<p>Con la presente ci opponiamo all'utilizzo dei dati di contatto pubblicati nell'ambito dell'obbligo di notifica legale per l'invio di materiale pubblicitario e informativo non richiesto. I gestori di questo sito web si riservano espressamente il diritto di intraprendere azioni legali in caso di invio non richiesto di informazioni pubblicitarie, come ad esempio le e-mail di spam.<\/p>\n<h2>4. raccolta di dati su questo sito web<\/h2>\n<h3>Biscotti<\/h3>\n<p>Le nostre pagine Internet utilizzano i cosiddetti \u201ecookie\u201c. I cookie sono piccoli file di testo e non causano alcun danno al vostro dispositivo finale. Vengono memorizzati sul vostro dispositivo temporaneamente per la durata di una sessione (cookie di sessione) o permanentemente (cookie permanenti). I cookie di sessione vengono cancellati automaticamente al termine della visita. I cookie permanenti rimangono memorizzati sul dispositivo finale dell'utente fino a quando non vengono eliminati dall'utente stesso o vengono eliminati automaticamente dal browser web.<\/p>\n<p>In alcuni casi, quando visitate il nostro sito web, possono essere memorizzati sul vostro dispositivo anche cookie di aziende terze (cookie di terze parti). Questi consentono a noi o a voi di utilizzare determinati servizi della societ\u00e0 terza (ad esempio, i cookie per l'elaborazione dei servizi di pagamento).<\/p>\n<p>I cookie hanno diverse funzioni. Molti cookie sono tecnicamente necessari, in quanto alcune funzioni del sito web non potrebbero funzionare senza di essi (ad esempio, la funzione del carrello o la visualizzazione di video). Altri cookie sono utilizzati per valutare il comportamento degli utenti o per visualizzare pubblicit\u00e0.<\/p>\n<p>I cookie necessari per eseguire il processo di comunicazione elettronica (cookie necessari) o per fornire determinate funzioni richieste dall'utente (cookie funzionali, ad es. per la funzione carrello) o per ottimizzare il sito web (ad es. cookie per misurare l'audience del web) vengono memorizzati sulla base dell'art. 6 par. 1 lett. f GDPR, a meno che non venga specificata un'altra base giuridica. Il gestore del sito web ha un interesse legittimo nella memorizzazione dei cookie per la fornitura tecnicamente priva di errori e ottimizzata dei propri servizi. Se \u00e8 stato richiesto il consenso alla memorizzazione dei cookie, i cookie in questione vengono memorizzati esclusivamente sulla base di tale consenso (art. 6 par. 1 lett. a GDPR); il consenso pu\u00f2 essere revocato in qualsiasi momento.<\/p>\n<p>Potete impostare il vostro browser in modo da essere informati sull'impostazione dei cookie e consentire i cookie solo in singoli casi, escludere l'accettazione dei cookie per determinati casi o in generale e attivare la cancellazione automatica dei cookie alla chiusura del browser. Se i cookie vengono disattivati, la funzionalit\u00e0 di questo sito web potrebbe essere limitata.<\/p>\n<p>Nel caso in cui i cookie vengano utilizzati da societ\u00e0 terze o per scopi di analisi, vi informeremo separatamente nel contesto della presente dichiarazione sulla protezione dei dati e, se necessario, richiederemo il vostro consenso.<\/p>\n<h3>Consenso ai cookie con Borlabs Cookie<\/h3>\n<p>Il nostro sito web utilizza la tecnologia di consenso dei cookie di Borlabs Cookie per ottenere il vostro consenso alla memorizzazione di determinati cookie nel vostro browser e per documentarlo in conformit\u00e0 con le norme sulla protezione dei dati. Il fornitore di questa tecnologia \u00e8 Borlabs - Benjamin A. Bornschein, Georg-Wilhelm-Str. 17, 21107 Amburgo, Germania (di seguito Borlabs).<\/p>\n<p>Quando accedete al nostro sito web, nel vostro browser viene memorizzato un cookie Borlabs, nel quale vengono memorizzati i consensi che avete dato o la revoca di tali consensi. Questi dati non vengono trasmessi al fornitore del cookie Borlabs.<\/p>\n<p>I dati raccolti saranno conservati fino a quando non ci chiederete di cancellarli o cancellerete voi stessi il cookie di Borlabs o fino a quando lo scopo della conservazione dei dati non sar\u00e0 pi\u00f9 valido. I periodi di conservazione obbligatori per legge rimangono inalterati. I dettagli sul trattamento dei dati da parte di Borlabs Cookie sono disponibili all'indirizzo\u00a0<a href=\"https:\/\/de.borlabs.io\/kb\/welche-daten-speichert-borlabs-cookie\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">https:\/\/de.borlabs.io\/kb\/welche-daten-speichert-borlabs-cookie\/<\/a><\/p>\n<p>La tecnologia di consenso dei cookie di Borlabs viene utilizzata per ottenere il consenso legalmente richiesto per l'utilizzo dei cookie. La base giuridica \u00e8 l'art. 6 comma 1 frase 1 lit. c GDPR.<\/p>\n<h3>File di log del server<\/h3>\n<p>Il fornitore delle pagine raccoglie e memorizza automaticamente le informazioni nei cosiddetti file di log del server, che il vostro browser ci trasmette automaticamente. Questi sono<\/p>\n<ul>\n<li>Tipo e versione del browser<\/li>\n<li>Sistema operativo utilizzato<\/li>\n<li>URL di riferimento<\/li>\n<li>Nome host del computer di accesso<\/li>\n<li>Ora della richiesta del server<\/li>\n<li>Indirizzo IP<\/li>\n<\/ul>\n<p>Questi dati non vengono uniti ad altre fonti di dati.<\/p>\n<p>Questi dati vengono raccolti sulla base dell'art. 6 comma 1 lett. f GDPR. Il gestore del sito web ha un interesse legittimo alla presentazione tecnicamente priva di errori e all'ottimizzazione del proprio sito web - a tal fine \u00e8 necessario registrare i file di log del server.<\/p>\n<h3>Modulo di contatto<\/h3>\n<p>Se ci inviate richieste di informazioni tramite il modulo di contatto, i vostri dati del modulo di richiesta, compresi i dati di contatto che ci avete fornito, saranno memorizzati da noi allo scopo di elaborare la richiesta e in caso di domande successive. Non trasmetteremo questi dati senza il vostro consenso.<\/p>\n<p>Questi dati vengono elaborati sulla base dell'art. 6 par. 1 lett. b GDPR se la vostra richiesta \u00e8 legata all'adempimento di un contratto o \u00e8 necessaria per l'attuazione di misure precontrattuali. In tutti gli altri casi, il trattamento si basa sul nostro legittimo interesse all'efficace elaborazione delle richieste rivolteci (art. 6 cpv. 1 lett. f GDPR) o sul vostro consenso (art. 6 cpv. 1 lett. a GDPR), qualora sia stato richiesto.<\/p>\n<p>Conserveremo i dati forniti dall'utente nel modulo di contatto fino a quando l'utente non ne richieder\u00e0 la cancellazione, non revocher\u00e0 il proprio consenso alla conservazione o non verr\u00e0 meno lo scopo della conservazione (ad esempio, dopo aver soddisfatto la richiesta). Le disposizioni di legge obbligatorie, in particolare i periodi di conservazione, rimangono inalterate.<\/p>\n<h3>Richiesta via e-mail, telefono o fax<\/h3>\n<p>Se ci contattate via e-mail, telefono o fax, la vostra richiesta, compresi tutti i dati personali (nome, richiesta), verr\u00e0 memorizzata ed elaborata da noi allo scopo di evadere la vostra richiesta. Non trasmetteremo questi dati senza il vostro consenso.<\/p>\n<p>Questi dati vengono elaborati sulla base dell'art. 6 par. 1 lett. b GDPR se la vostra richiesta \u00e8 legata all'adempimento di un contratto o \u00e8 necessaria per l'attuazione di misure precontrattuali. In tutti gli altri casi, il trattamento si basa sul nostro legittimo interesse all'efficace elaborazione delle richieste rivolteci (art. 6 cpv. 1 lett. f GDPR) o sul vostro consenso (art. 6 cpv. 1 lett. a GDPR), qualora sia stato richiesto.<\/p>\n<p>I dati che ci inviate tramite le richieste di contatto rimarranno presso di noi fino a quando non ci chiederete di cancellarli, non revocherete il vostro consenso alla memorizzazione o lo scopo della memorizzazione dei dati non sar\u00e0 pi\u00f9 valido (ad esempio dopo l'elaborazione della vostra richiesta). Le disposizioni di legge obbligatorie, in particolare i periodi di conservazione previsti dalla legge, rimangono inalterate.<\/p>\n<h3>Registrazione su questo sito web<\/h3>\n<p>\u00c8 possibile registrarsi su questo sito web per poter utilizzare ulteriori funzioni del sito. I dati inseriti verranno utilizzati esclusivamente per l'utilizzo dell'offerta o del servizio per il quale ci si \u00e8 registrati. Le informazioni obbligatorie richieste durante la registrazione devono essere fornite integralmente. In caso contrario, rifiuteremo la vostra registrazione.<\/p>\n<p>In caso di modifiche importanti, ad esempio per quanto riguarda la portata dell'offerta o modifiche tecnicamente necessarie, utilizzeremo l'indirizzo e-mail fornito durante la registrazione per informarvi in questo modo.<\/p>\n<p>I dati inseriti al momento della registrazione vengono elaborati allo scopo di implementare il rapporto con l'utente stabilito dalla registrazione e, se necessario, per l'avvio di ulteriori contratti (art. 6 par. 1 lett. b GDPR).<\/p>\n<p>I dati raccolti durante la registrazione saranno conservati da noi per tutto il tempo in cui l'utente sar\u00e0 registrato su questo sito web e saranno poi cancellati. I periodi di conservazione previsti dalla legge rimangono inalterati.<\/p>\n<h3>Funzione di commento su questo sito web<\/h3>\n<p>Per la funzione di commento di questa pagina, oltre al vostro commento, verranno salvate informazioni sull'ora di creazione del commento, il vostro indirizzo e-mail e, se non state postando in forma anonima, il nome utente che avete scelto.<\/p>\n<p><strong>Memorizzazione dell'indirizzo IP<\/strong><\/p>\n<p>La nostra funzione di commento memorizza gli indirizzi IP degli utenti che pubblicano commenti. Poich\u00e9 non controlliamo i commenti su questo sito prima che vengano attivati, abbiamo bisogno di questi dati per poter agire contro l'autore in caso di violazioni legali come insulti o propaganda.<\/p>\n<p><strong>Iscriviti ai commenti<\/strong><\/p>\n<p>Come utente del sito, \u00e8 possibile iscriversi ai commenti dopo essersi registrati. Riceverete un'e-mail di conferma per verificare se siete i proprietari dell'indirizzo e-mail fornito. \u00c8 possibile annullare l'iscrizione a questa funzione in qualsiasi momento tramite un link presente nelle e-mail informative. In questo caso, i dati inseriti al momento dell'iscrizione ai commenti saranno cancellati; tuttavia, se ci avete trasmesso questi dati per altri scopi e in altri luoghi (ad esempio, l'iscrizione alla newsletter), questi dati rimarranno presso di noi.<\/p>\n<p><strong>Durata di conservazione dei commenti<\/strong><\/p>\n<p>I commenti e i relativi dati (ad es. l'indirizzo IP) vengono memorizzati e rimangono su questo sito web fino a quando il contenuto commentato non viene completamente cancellato o i commenti devono essere cancellati per motivi legali (ad es. commenti offensivi).<\/p>\n<p><strong>Base giuridica<\/strong><\/p>\n<p>I commenti vengono memorizzati sulla base del vostro consenso (art. 6 par. 1 lett. a GDPR). Potete revocare il vostro consenso in qualsiasi momento. Tutto ci\u00f2 che dovete fare \u00e8 inviarci un'e-mail informale. La legalit\u00e0 delle operazioni di trattamento dei dati gi\u00e0 avvenute rimane inalterata dalla revoca.<\/p>\n<h2>5. i social media<\/h2>\n<h3>Strumento di condivisione sicura di eRecht24<\/h3>\n<p>I contenuti di questo sito web possono essere condivisi su social network come Facebook, Twitter &amp; Co. nel rispetto delle norme sulla protezione dei dati. Questa pagina utilizza il\u00a0<a href=\"https:\/\/www.e-recht24.de\/erecht24-safe-sharing.html\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Strumento di condivisione sicura di eRecht24<\/a>. Questo strumento stabilisce un contatto diretto tra le reti e gli utenti solo quando l'utente clicca attivamente su uno di questi pulsanti. Il clic sul pulsante costituisce un consenso ai sensi dell'art. 6 par. 1 lett. a GDPR. Tale consenso pu\u00f2 essere revocato in qualsiasi momento con effetto per il futuro.<\/p>\n<p>Questo strumento non trasferisce automaticamente i dati dell'utente agli operatori di queste piattaforme. Se l'utente ha effettuato l'accesso a uno dei social network, quando utilizza i pulsanti sociali di Facebook, Twitter &amp; Co. appare una finestra informativa in cui l'utente pu\u00f2 confermare il testo prima di inviarlo.<\/p>\n<p>I nostri utenti possono condividere i contenuti di questo sito sui social network nel rispetto delle norme sulla protezione dei dati, senza che gli operatori della rete creino profili di navigazione completi.<\/p>\n<h3>Plugin per Facebook (pulsante \"Mi piace\" e \"Condividi\")<\/h3>\n<p>Su questo sito web sono integrati i plugin del social network Facebook. Il fornitore di questo servizio \u00e8 Facebook Ireland Limited, 4 Grand Canal Square, Dublino 2, Irlanda. Tuttavia, secondo Facebook, i dati raccolti vengono trasferiti anche negli Stati Uniti e in altri Paesi terzi.<\/p>\n<p>I plugin di Facebook sono riconoscibili dal logo di Facebook o dal pulsante \u201eMi piace\u201c su questo sito web. Una panoramica dei plugin di Facebook \u00e8 disponibile qui:\u00a0<a href=\"https:\/\/developers.facebook.com\/docs\/plugins\/?locale=de_DE\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">https:\/\/developers.facebook.com\/docs\/plugins\/?locale=de_DE<\/a>.<\/p>\n<p>Quando visitate questo sito web, viene stabilita una connessione diretta tra il vostro browser e il server di Facebook tramite il plugin. Facebook riceve cos\u00ec l'informazione che avete visitato questo sito web con il vostro indirizzo IP. Se cliccate sul pulsante \u201eMi piace\u201c di Facebook mentre siete connessi al vostro account Facebook, potete collegare il contenuto di questo sito web al vostro profilo Facebook. Ci\u00f2 consente a Facebook di associare la visita a questo sito web al vostro account utente. Desideriamo sottolineare che, in qualit\u00e0 di fornitore delle pagine, non siamo a conoscenza del contenuto dei dati trasmessi n\u00e9 del loro utilizzo da parte di Facebook. Ulteriori informazioni in merito sono disponibili nell'informativa sulla privacy di Facebook all'indirizzo\u00a0<a href=\"https:\/\/de-de.facebook.com\/privacy\/explanation\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">https:\/\/de-de.facebook.com\/privacy\/explanation<\/a>.<\/p>\n<p>Se non volete che Facebook possa associare la vostra visita a questo sito web al vostro account utente di Facebook, siete pregati di disconnettervi dal vostro account utente di Facebook.<\/p>\n<p>I plugin di Facebook vengono utilizzati sulla base dell'art. 6 comma 1 lett. f GDPR. Il gestore del sito web ha un interesse legittimo alla pi\u00f9 ampia visibilit\u00e0 possibile sui social media. Se \u00e8 stato richiesto un consenso, il trattamento avviene esclusivamente sulla base dell'art. 6 par. 1 lett. a GDPR; il consenso pu\u00f2 essere revocato in qualsiasi momento.<\/p>\n<h3>Plugin Instagram<\/h3>\n<p>Le funzioni del servizio Instagram sono integrate in questo sito web. Queste funzioni sono offerte da Instagram Inc., 1601 Willow Road, Menlo Park, CA 94025, USA.<\/p>\n<p>Se avete effettuato l'accesso al vostro account Instagram, potete collegare il contenuto di questo sito web al vostro profilo Instagram facendo clic sul pulsante Instagram. Ci\u00f2 consente a Instagram di associare la vostra visita a questo sito web al vostro account utente. Desideriamo sottolineare che, in qualit\u00e0 di fornitore delle pagine, non siamo a conoscenza del contenuto dei dati trasmessi n\u00e9 del loro utilizzo da parte di Instagram.<\/p>\n<p>I dati vengono memorizzati e analizzati sulla base dell'art. 6 par. 1 lett. f GDPR. Il gestore del sito web ha un interesse legittimo alla pi\u00f9 ampia visibilit\u00e0 possibile sui social media. Se \u00e8 stato richiesto un consenso corrispondente, il trattamento avviene esclusivamente sulla base dell'art. 6 par. 1 lett. a GDPR; il consenso pu\u00f2 essere revocato in qualsiasi momento.<\/p>\n<p>Ulteriori informazioni al riguardo sono disponibili nell'informativa sulla privacy di Instagram:\u00a0<a href=\"https:\/\/instagram.com\/about\/legal\/privacy\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">https:\/\/instagram.com\/about\/legal\/privacy\/<\/a>.<\/p>\n<h3>Plugin Pinterest<\/h3>\n<p>Su questo sito web utilizziamo i social plugin del social network Pinterest, gestito da Pinterest Inc., 808 Brannan Street, San Francisco, CA 94103-490, USA (\u201ePinterest\u201c).<\/p>\n<p>Quando visitate una pagina che contiene un plugin di questo tipo, il vostro browser stabilisce una connessione diretta ai server di Pinterest. Il plugin trasmette i dati di log al server di Pinterest negli Stati Uniti. Questi dati di log possono contenere il vostro indirizzo IP, l'indirizzo dei siti web visitati che contengono anche funzioni di Pinterest, il tipo e le impostazioni del browser, la data e l'ora della richiesta, il vostro utilizzo di Pinterest e dei cookie.<\/p>\n<p>I dati vengono memorizzati e analizzati sulla base dell'art. 6 par. 1 lett. f GDPR. Il gestore del sito web ha un interesse legittimo alla pi\u00f9 ampia visibilit\u00e0 possibile sui social media. Se \u00e8 stato richiesto un consenso corrispondente, il trattamento avviene esclusivamente sulla base dell'art. 6 par. 1 lett. a GDPR; il consenso pu\u00f2 essere revocato in qualsiasi momento.<\/p>\n<p>Ulteriori informazioni sulle finalit\u00e0, l'ambito e l'ulteriore elaborazione e utilizzo dei dati da parte di Pinterest, nonch\u00e9 sui diritti e le possibilit\u00e0 di tutela della privacy dell'utente, sono disponibili nell'informativa sulla privacy di Pinterest:\u00a0<a href=\"https:\/\/policy.pinterest.com\/de\/privacy-policy\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">https:\/\/policy.pinterest.com\/de\/privacy-policy<\/a>.<\/p>\n<h2>6. strumenti di analisi e pubblicit\u00e0<\/h2>\n<h3>Google Analytics<\/h3>\n<p>Questo sito web utilizza le funzioni del servizio di analisi web Google Analytics. Il fornitore \u00e8 Google Ireland Limited (\u201eGoogle\u201c), Gordon House, Barrow Street, Dublino 4, Irlanda.<\/p>\n<p>Google Analytics utilizza i cosiddetti \u201ecookie\u201c. Si tratta di file di testo che vengono memorizzati sul vostro computer e che consentono di analizzare il vostro utilizzo del sito web. Le informazioni generate dal cookie sull'utilizzo del sito web da parte dell'utente vengono solitamente trasmesse a un server di Google negli Stati Uniti e l\u00ec memorizzate.<\/p>\n<p>La memorizzazione dei cookie di Google Analytics e l'utilizzo di questo strumento di analisi si basano sull'art. 6 comma 1 lett. f GDPR. Il gestore del sito web ha un interesse legittimo ad analizzare il comportamento degli utenti per ottimizzare il proprio sito web e la propria pubblicit\u00e0. Se \u00e8 stato richiesto un consenso corrispondente (ad es. consenso alla memorizzazione dei cookie), il trattamento avviene esclusivamente sulla base dell'art. 6 par. 1 lett. a GDPR; il consenso pu\u00f2 essere revocato in qualsiasi momento.<\/p>\n<p><strong>Anonimizzazione dell'IP<\/strong><\/p>\n<p>Su questo sito web abbiamo attivato la funzione di anonimizzazione dell'IP. Ci\u00f2 significa che il vostro indirizzo IP verr\u00e0 troncato da Google all'interno degli Stati membri dell'Unione Europea o in altri Stati firmatari dell'Accordo sullo Spazio Economico Europeo prima di essere trasmesso agli USA. Solo in casi eccezionali l'indirizzo IP completo verr\u00e0 trasmesso a un server di Google negli USA e l\u00ec troncato. Su incarico del gestore di questo sito web, Google utilizzer\u00e0 queste informazioni per analizzare l'utilizzo del sito web da parte dell'utente, per redigere rapporti sulle attivit\u00e0 del sito web e per fornire al gestore del sito web altri servizi relativi alle attivit\u00e0 del sito web e all'utilizzo di Internet. L'indirizzo IP trasmesso dal vostro browser nell'ambito di Google Analytics non verr\u00e0 unito ad altri dati di Google.<\/p>\n<p><strong>Plugin del browser<\/strong><\/p>\n<p>Potete rifiutarvi di usare i cookie selezionando l'impostazione appropriata sul vostro browser; tuttavia, tenete presente che in tal caso potreste non essere in grado di utilizzare tutte le funzionalit\u00e0 di questo sito web. Potete inoltre impedire a Google di raccogliere i dati generati dal cookie e relativi al vostro utilizzo del sito web (compreso il vostro indirizzo IP) e di elaborarli da parte di Google scaricando e installando il plug-in del browser disponibile al seguente link:\u00a0<a href=\"https:\/\/tools.google.com\/dlpage\/gaoptout?hl=de\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">https:\/\/tools.google.com\/dlpage\/gaoptout?hl=de<\/a>.<\/p>\n<p><strong>Obiezione alla raccolta dei dati<\/strong><\/p>\n<p>Potete impedire la raccolta dei vostri dati da parte di Google Analytics cliccando sul seguente link. Verr\u00e0 impostato un cookie di opt-out per impedire la raccolta dei vostri dati nelle visite future a questo sito web:\u00a0<a>Disattivare Google Analytics<\/a>.<\/p>\n<p>Per ulteriori informazioni sul trattamento dei dati degli utenti da parte di Google Analytics, consultare l'informativa sulla privacy di Google:\u00a0<a href=\"https:\/\/support.google.com\/analytics\/answer\/6004245?hl=de\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">https:\/\/support.google.com\/analytics\/answer\/6004245?hl=de<\/a>.<\/p>\n<p><strong>Elaborazione dell'ordine<\/strong><\/p>\n<p>Abbiamo stipulato un contratto per l'elaborazione degli ordini con Google e, per l'utilizzo di Google Analytics, ci atteniamo pienamente ai severi requisiti delle autorit\u00e0 tedesche per la protezione dei dati.<\/p>\n<p><strong>Caratteristiche demografiche in Google Analytics<\/strong><\/p>\n<p>Questo sito web utilizza la funzione \u201ecaratteristiche demografiche\u201c di Google Analytics. In questo modo \u00e8 possibile creare rapporti che contengono indicazioni sull'et\u00e0, il sesso e gli interessi dei visitatori del sito. Questi dati provengono dalla pubblicit\u00e0 basata sugli interessi di Google e dai dati dei visitatori di fornitori terzi. Questi dati non possono essere assegnati a una persona specifica. Potete disattivare questa funzione in qualsiasi momento tramite le impostazioni pubblicitarie del vostro account Google o vietare in generale la raccolta dei vostri dati da parte di Google Analytics come descritto nella sezione \u201eObiezione alla raccolta dei dati\u201c.<\/p>\n<p><strong>Durata della conservazione<\/strong><\/p>\n<p>I dati memorizzati da Google a livello di utente e di evento che sono collegati a cookie, ID utente o ID pubblicitari (ad es. cookie DoubleClick, ID pubblicitari Android) vengono anonimizzati o cancellati dopo 14 mesi. I dettagli sono disponibili al seguente link:\u00a0<a href=\"https:\/\/support.google.com\/analytics\/answer\/7667196?hl=de\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">https:\/\/support.google.com\/analytics\/answer\/7667196?hl=de<\/a><\/p>\n<h3>Google AdSense (non personalizzato)<\/h3>\n<p>Questo sito web utilizza Google AdSense, un servizio per l'integrazione di annunci pubblicitari. Il fornitore \u00e8 Google Ireland Limited (\u201eGoogle\u201c), Gordon House, Barrow Street, Dublino 4, Irlanda.<\/p>\n<p>Utilizziamo Google AdSense in modalit\u00e0 \u201enon personalizzata\u201c. A differenza della modalit\u00e0 personalizzata, gli annunci pubblicitari non si basano quindi sul vostro comportamento precedente e non viene creato un profilo utente per voi. Per selezionare gli annunci vengono invece utilizzate le cosiddette \u201einformazioni contestuali\u201c. Le pubblicit\u00e0 selezionate si basano, ad esempio, sulla posizione dell'utente, sul contenuto del sito web in cui si trova o sui termini di ricerca correnti. Per saperne di pi\u00f9 sulle differenze tra targeting personalizzato e non personalizzato con Google AdSense, cliccate qui:\u00a0<a href=\"https:\/\/support.google.com\/adsense\/answer\/9007336\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">https:\/\/support.google.com\/adsense\/answer\/9007336<\/a>.<\/p>\n<p>Si noti che i cookie possono essere memorizzati anche quando si utilizza Google Adsense in modalit\u00e0 non personalizzata. Secondo Google, questi vengono utilizzati per combattere le frodi e gli abusi. I cookie rimangono sul dispositivo finale dell'utente fino a quando non vengono cancellati.<\/p>\n<p>L'utilizzo di Google Adsense in modalit\u00e0 non personalizzata si basa sull'art. 6 comma 1 lett. f GDPR. Abbiamo un interesse legittimo ad analizzare il comportamento degli utenti per ottimizzare il nostro sito web e la nostra pubblicit\u00e0. Se \u00e8 stato richiesto un consenso corrispondente (ad es. consenso alla memorizzazione dei cookie), il trattamento avviene esclusivamente sulla base dell'art. 6 par. 1 lett. a GDPR; il consenso pu\u00f2 essere revocato in qualsiasi momento.<\/p>\n<p>Google \u00e8 certificata in conformit\u00e0 con il Privacy Shield UE-USA. Il Privacy Shield \u00e8 un accordo tra l'Unione Europea e gli Stati Uniti che mira a garantire il rispetto degli standard europei di protezione dei dati per l'elaborazione dei dati negli Stati Uniti. Ogni azienda certificata nell'ambito del Privacy Shield si impegna a rispettare questi standard di protezione dei dati.<\/p>\n<p>\u00c8 possibile personalizzare le impostazioni pubblicitarie nel proprio account utente. Per farlo, cliccate sul seguente link e accedete:\u00a0<a href=\"https:\/\/adssettings.google.com\/authenticated\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">https:\/\/adssettings.google.com\/authenticated<\/a>.<\/p>\n<p>Ulteriori informazioni sulle tecnologie pubblicitarie di Google sono disponibili qui:<br \/>\n<a href=\"https:\/\/policies.google.com\/technologies\/ads\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">https:\/\/policies.google.com\/technologies\/ads<\/a><br \/>\n<a href=\"https:\/\/www.google.de\/intl\/de\/policies\/privacy\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">https:\/\/www.google.de\/intl\/de\/policies\/privacy\/<\/a>.<\/p>\n<h3>Remarketing di Google Analytics<\/h3>\n<p>Questo sito web utilizza le funzioni di Google Analytics Remarketing insieme alle funzioni cross-device di Google Ads e Google DoubleClick. Il fornitore \u00e8 Google Ireland Limited (\u201eGoogle\u201c), Gordon House, Barrow Street, Dublino 4, Irlanda.<\/p>\n<p>Questa funzione consente di collegare i gruppi target pubblicitari creati con Google Analytics Remarketing con le funzioni cross-device di Google Ads e Google DoubleClick. In questo modo, i messaggi pubblicitari personalizzati e basati sugli interessi che sono stati adattati all'utente in base al suo precedente utilizzo e al suo comportamento di navigazione su un dispositivo finale (ad esempio, il telefono cellulare) possono essere visualizzati anche su un altro dispositivo finale (ad esempio, il tablet o il PC).<\/p>\n<p>Se avete dato il vostro consenso, Google collegher\u00e0 la vostra cronologia di navigazione sul web e nelle app al vostro account Google a questo scopo. In questo modo, gli stessi messaggi pubblicitari personalizzati possono essere visualizzati su tutti i dispositivi su cui si accede con il proprio account Google.<\/p>\n<p>Per supportare questa funzione, Google Analytics raccoglie ID utente autenticati da Google che vengono temporaneamente collegati ai nostri dati di Google Analytics al fine di definire e creare gruppi target per la pubblicit\u00e0 cross-device.<\/p>\n<p>Potete opporvi in modo permanente al remarketing\/targeting cross-device disattivando la pubblicit\u00e0 personalizzata; per farlo, seguite questo link:\u00a0<a href=\"https:\/\/www.google.com\/settings\/ads\/onweb\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">https:\/\/www.google.com\/settings\/ads\/onweb\/<\/a>.<\/p>\n<p>L'aggregazione dei dati raccolti nel vostro account Google si basa esclusivamente sul vostro consenso, che potete dare o revocare a Google (art. 6 par. 1 lett. a GDPR). Per i processi di raccolta dei dati che non vengono aggregati nel vostro account Google (ad esempio perch\u00e9 non avete un account Google o vi siete opposti all'aggregazione), la raccolta dei dati si basa sull'art. 6 par. 1 lett. f GDPR. Il legittimo interesse deriva dal fatto che il gestore del sito web ha un interesse nell'analisi anonima dei visitatori del sito web a fini pubblicitari.<\/p>\n<p>Ulteriori informazioni e le disposizioni sulla protezione dei dati sono disponibili nell'informativa sulla privacy di Google all'indirizzo:\u00a0<a href=\"https:\/\/policies.google.com\/technologies\/ads?hl=de\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">https:\/\/policies.google.com\/technologies\/ads?hl=de<\/a>.<\/p>\n<h3>Annunci di Google e monitoraggio delle conversioni di Google<\/h3>\n<p>Questo sito web utilizza Google Ads. Google Ads \u00e8 un programma di pubblicit\u00e0 online di Google Ireland Limited (\u201eGoogle\u201c), Gordon House, Barrow Street, Dublino 4, Irlanda.<\/p>\n<p>Nell'ambito di Google Ads, utilizziamo il cosiddetto conversion tracking. Quando si fa clic su un annuncio pubblicitario pubblicato da Google, viene impostato un cookie per il monitoraggio delle conversioni. I cookie sono piccoli file di testo che il browser Internet memorizza sul computer dell'utente. Questi cookie perdono la loro validit\u00e0 dopo 30 giorni e non vengono utilizzati per identificare personalmente l'utente. Se l'utente visita determinate pagine di questo sito web e il cookie non \u00e8 ancora scaduto, Google e noi possiamo riconoscere che l'utente ha cliccato sull'annuncio ed \u00e8 stato reindirizzato a questa pagina.<\/p>\n<p>Ogni cliente di Google Ads riceve un cookie diverso. I cookie non possono essere tracciati attraverso i siti web dei clienti di Google Ads. Le informazioni raccolte tramite il cookie di conversione vengono utilizzate per generare statistiche di conversione per i clienti di Google Ads che hanno optato per il conversion tracking. Ai clienti viene comunicato il numero totale di utenti che hanno fatto clic sul loro annuncio e sono stati reindirizzati a una pagina con un tag di monitoraggio della conversione. Tuttavia, non ricevono alcuna informazione che possa essere utilizzata per identificare personalmente gli utenti. Se non desiderate partecipare al monitoraggio, potete opporvi a questo utilizzo disattivando facilmente il cookie di Google Conversion Tracking tramite il vostro browser Internet nelle impostazioni utente. In questo modo non sarete inclusi nelle statistiche di conversion tracking.<\/p>\n<p>La memorizzazione dei \u201ecookie di conversione\u201c e l'utilizzo di questo strumento di tracciamento si basano sull'art. 6 comma 1 lett. f GDPR. Il gestore del sito web ha un interesse legittimo ad analizzare il comportamento degli utenti per ottimizzare il proprio sito web e la propria pubblicit\u00e0. Se \u00e8 stato richiesto un consenso corrispondente (ad es. consenso alla memorizzazione dei cookie), il trattamento avviene esclusivamente sulla base dell'art. 6 par. 1 lett. a GDPR; il consenso pu\u00f2 essere revocato in qualsiasi momento.<\/p>\n<p>Per ulteriori informazioni su Google Ads e Google Conversion Tracking, consultare l'informativa sulla privacy di Google:\u00a0<a href=\"https:\/\/policies.google.com\/privacy?hl=de\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">https:\/\/policies.google.com\/privacy?hl=de<\/a>.<\/p>\n<p>Potete impostare il vostro browser in modo da essere informati sull'impostazione dei cookie e consentire i cookie solo in singoli casi, escludere l'accettazione dei cookie per determinati casi o in generale e attivare la cancellazione automatica dei cookie alla chiusura del browser. Se i cookie vengono disattivati, la funzionalit\u00e0 di questo sito web potrebbe essere limitata.<\/p>\n<h3>Google DoubleClick<\/h3>\n<p>Questo sito web utilizza le funzioni di Google DoubleClick. Il fornitore \u00e8 Google LLC, 1600 Amphitheatre Parkway, Mountain View, CA 94043, USA, (di seguito \u201eDoubleClick\u201c).<\/p>\n<p>DoubleClick viene utilizzato per mostrare annunci pubblicitari basati sugli interessi in tutta la rete pubblicitaria di Google. Con l'aiuto di DoubleClick, le pubblicit\u00e0 possono essere mirate agli interessi del rispettivo spettatore.  Ad esempio, i nostri annunci possono essere visualizzati nei risultati di ricerca di Google o nei banner pubblicitari collegati a DoubleClick.<\/p>\n<p>Per poter mostrare agli utenti pubblicit\u00e0 basata sugli interessi, DoubleClick deve essere in grado di riconoscere il rispettivo utente. A tal fine, nel browser dell'utente viene memorizzato un cookie, nel quale vengono memorizzati i siti web visitati dall'utente, i clic e varie altre informazioni. Queste informazioni vengono riassunte in un profilo utente pseudonimo al fine di mostrare pubblicit\u00e0 basata sugli interessi all'utente in questione.<\/p>\n<p>Google DoubleClick viene utilizzato nell'interesse di misure pubblicitarie mirate. Ci\u00f2 costituisce un interesse legittimo ai sensi dell'art. 6 comma 1 lett. f GDPR. Se \u00e8 stato richiesto un consenso corrispondente (ad es. consenso alla memorizzazione dei cookie), il trattamento avviene esclusivamente sulla base dell'art. 6 par. 1 lett. a GDPR; il consenso pu\u00f2 essere revocato in qualsiasi momento.<\/p>\n<p>\u00c8 possibile impostare il browser in modo che non memorizzi pi\u00f9 i cookie. Tuttavia, ci\u00f2 potrebbe limitare le funzioni del sito web a cui \u00e8 possibile accedere. Si noti inoltre che DoubleClick pu\u00f2 utilizzare anche altre tecnologie per creare profili utente. La disattivazione dei cookie non garantisce quindi che non vengano pi\u00f9 creati profili utente.<\/p>\n<p>Ulteriori informazioni su come opporsi agli annunci pubblicitari visualizzati da Google sono disponibili ai seguenti link:\u00a0<a href=\"https:\/\/policies.google.com\/technologies\/ads\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">https:\/\/policies.google.com\/technologies\/ads<\/a>\u00a0e\u00a0<a href=\"https:\/\/adssettings.google.com\/authenticated\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">https:\/\/adssettings.google.com\/authenticated<\/a>.<\/p>\n<h3>Pixel di Facebook<\/h3>\n<p>Questo sito web utilizza il pixel di azione dei visitatori di Facebook per misurare le conversioni. Il fornitore di questo servizio \u00e8 Facebook Ireland Limited, 4 Grand Canal Square, Dublino 2, Irlanda. Tuttavia, secondo Facebook, i dati raccolti vengono trasferiti anche negli Stati Uniti e in altri Paesi terzi.<\/p>\n<p>Ci\u00f2 consente di tracciare il comportamento dei visitatori del sito dopo che sono stati reindirizzati al sito web del fornitore facendo clic su un annuncio di Facebook. Ci\u00f2 consente di valutare l'efficacia degli annunci di Facebook a fini statistici e di ricerca di mercato e di ottimizzare le future misure pubblicitarie.<\/p>\n<p>I dati raccolti sono anonimi per noi, in quanto gestori di questo sito web; non possiamo trarre alcuna conclusione sull'identit\u00e0 dell'utente. Tuttavia, i dati vengono memorizzati ed elaborati da Facebook, in modo che sia possibile un collegamento con il rispettivo profilo utente e che Facebook possa utilizzare i dati per i propri scopi pubblicitari, in conformit\u00e0 con le norme di legge.\u00a0<a href=\"https:\/\/de-de.facebook.com\/about\/privacy\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Informativa sull'utilizzo dei dati di Facebook<\/a>\u00a0pu\u00f2 utilizzare. Ci\u00f2 consente a Facebook di inserire annunci pubblicitari sulle pagine di Facebook e al di fuori di Facebook. Questo utilizzo dei dati non pu\u00f2 essere influenzato da noi in quanto gestori del sito.<\/p>\n<p>L'utilizzo del Pixel di Facebook si basa sull'art. 6 par. 1 lett. f GDPR. Il gestore del sito web ha un interesse legittimo a misure pubblicitarie efficaci, compresi i social media. Se \u00e8 stato richiesto un consenso corrispondente (ad es. consenso alla memorizzazione dei cookie), il trattamento avviene esclusivamente sulla base dell'art. 6 par. 1 lett. a GDPR; il consenso pu\u00f2 essere revocato in qualsiasi momento.<\/p>\n<p>Per ulteriori informazioni sulla protezione della privacy, consultare l'informativa sulla privacy di Facebook:\u00a0<a href=\"https:\/\/de-de.facebook.com\/about\/privacy\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">https:\/\/de-de.facebook.com\/about\/privacy\/<\/a>.<\/p>\n<p>\u00c8 inoltre possibile utilizzare la funzione di remarketing \u201eCustom Audiences\u201c nella sezione delle impostazioni degli annunci alla voce\u00a0<a href=\"https:\/\/www.facebook.com\/ads\/preferences\/?entry_product=ad_settings_screen\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">https:\/\/www.facebook.com\/ads\/preferences\/?entry_product=ad_settings_screen<\/a>\u00a0disattivarlo. Per farlo, \u00e8 necessario aver effettuato l'accesso a Facebook.<\/p>\n<p>Se non avete un account Facebook, potete disattivare la pubblicit\u00e0 basata sull'uso da Facebook sul sito web della European Interactive Digital Advertising Alliance:\u00a0<a href=\"http:\/\/www.youronlinechoices.com\/de\/praferenzmanagement\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">http:\/\/www.youronlinechoices.com\/de\/praferenzmanagement\/<\/a>.<\/p>\n<h2>7. plugin e strumenti<\/h2>\n<h3>YouTube con protezione estesa dei dati<\/h3>\n<p>Questo sito web incorpora video da YouTube. Il gestore delle pagine \u00e8 Google Ireland Limited (\u201eGoogle\u201c), Gordon House, Barrow Street, Dublino 4, Irlanda.<\/p>\n<p>Utilizziamo YouTube in modalit\u00e0 di protezione dei dati estesa. Secondo YouTube, questa modalit\u00e0 significa che YouTube non memorizza alcuna informazione sui visitatori di questo sito web prima che questi guardino il video. Tuttavia, il trasferimento di dati ai partner di YouTube non \u00e8 necessariamente escluso dalla modalit\u00e0 di protezione estesa dei dati. Ad esempio, YouTube stabilisce una connessione alla rete di Google DoubleClick indipendentemente dalla visione di un video.<\/p>\n<p>Non appena si avvia un video di YouTube su questo sito, viene stabilita una connessione ai server di YouTube. Questo comunica al server di YouTube quali pagine avete visitato. Se siete collegati al vostro account YouTube, consentite a YouTube di assegnare il vostro comportamento di navigazione direttamente al vostro profilo personale. Potete evitare che ci\u00f2 avvenga disconnettendovi dal vostro account YouTube.<\/p>\n<p>Inoltre, YouTube pu\u00f2 memorizzare diversi cookie sul dispositivo finale dell'utente dopo l'avvio di un video. Con l'aiuto di questi cookie, YouTube pu\u00f2 ottenere informazioni sui visitatori di questo sito web. Queste informazioni vengono utilizzate, tra l'altro, per registrare le statistiche dei video, migliorare la facilit\u00e0 d'uso e prevenire i tentativi di frode. I cookie rimangono sul vostro dispositivo finch\u00e9 non li cancellate.<\/p>\n<p>Dopo l'avvio di un video di YouTube, possono essere attivate ulteriori operazioni di elaborazione dei dati sulle quali non abbiamo alcuna influenza.<\/p>\n<p>L'utilizzo di YouTube avviene nell'interesse di una presentazione accattivante delle nostre offerte online. Ci\u00f2 costituisce un interesse legittimo ai sensi dell'art. 6 comma 1 lett. f GDPR. Se \u00e8 stato richiesto un consenso corrispondente, il trattamento avviene esclusivamente sulla base dell'art. 6 par. 1 lett. a GDPR; il consenso pu\u00f2 essere revocato in qualsiasi momento.<\/p>\n<p>Ulteriori informazioni sulla protezione dei dati in YouTube sono disponibili nell'informativa sulla privacy all'indirizzo:\u00a0<a href=\"https:\/\/policies.google.com\/privacy?hl=de\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">https:\/\/policies.google.com\/privacy?hl=de<\/a>.<\/p>\n<h3>Vimeo<\/h3>\n<p>Questo sito web utilizza i plugin del portale video Vimeo. Il fornitore \u00e8 Vimeo Inc, 555 West 18th Street, New York, New York 10011, USA.<\/p>\n<p>Quando visitate una delle nostre pagine dotate di un plugin Vimeo, viene stabilita una connessione con i server Vimeo. Il server di Vimeo viene informato su quale delle nostre pagine avete visitato. Vimeo ottiene anche il vostro indirizzo IP. Questo vale anche nel caso in cui l'utente non abbia effettuato l'accesso a Vimeo o non disponga di un account Vimeo. Le informazioni raccolte da Vimeo vengono trasmesse al server di Vimeo negli Stati Uniti.<\/p>\n<p>Se si accede al proprio account Vimeo, si consente a Vimeo di assegnare il proprio comportamento di navigazione direttamente al proprio profilo personale. \u00c8 possibile evitare che ci\u00f2 avvenga disconnettendosi dal proprio account Vimeo.<\/p>\n<p>L'utilizzo di Vimeo avviene nell'interesse di una presentazione accattivante delle nostre offerte online. Ci\u00f2 costituisce un interesse legittimo ai sensi dell'art. 6 comma 1 lett. f GDPR. Se \u00e8 stato richiesto un consenso corrispondente, il trattamento avviene esclusivamente sulla base dell'art. 6 par. 1 lett. a GDPR; il consenso pu\u00f2 essere revocato in qualsiasi momento.<\/p>\n<p>Ulteriori informazioni sul trattamento dei dati degli utenti sono disponibili nell'informativa sulla privacy di Vimeo all'indirizzo:\u00a0<a href=\"https:\/\/vimeo.com\/privacy\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">https:\/\/vimeo.com\/privacy<\/a>.<\/p>\n<h3>Google Web Fonts<\/h3>\n<p>Questo sito utilizza i cosiddetti web font forniti da Google per la visualizzazione standardizzata dei caratteri. I font di Google sono installati localmente. Non vi \u00e8 alcun collegamento con i server di Google.<\/p>\n<p>Ulteriori informazioni su Google Web Fonts sono disponibili all'indirizzo\u00a0<a href=\"https:\/\/developers.google.com\/fonts\/faq\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">https:\/\/developers.google.com\/fonts\/faq<\/a>\u00a0e nell'informativa sulla privacy di Google:\u00a0<a href=\"https:\/\/policies.google.com\/privacy?hl=de\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">https:\/\/policies.google.com\/privacy?hl=de<\/a>.<\/p>\n<h3>Caratteri Adobe<\/h3>\n<p>Questo sito web utilizza i font web di Adobe per la visualizzazione standardizzata di alcuni caratteri. Il fornitore \u00e8 Adobe Systems Incorporated, 345 Park Avenue, San Jose, CA 95110-2704, USA (Adobe).<\/p>\n<p>Quando si accede a questo sito web, il browser carica i font necessari direttamente da Adobe per visualizzarli correttamente sul dispositivo. In questo modo, il browser stabilisce una connessione con i server di Adobe negli Stati Uniti. In questo modo Adobe viene a conoscenza del fatto che questo sito web \u00e8 stato visitato tramite il vostro indirizzo IP. Secondo Adobe, non vengono memorizzati cookie quando vengono forniti i font.<\/p>\n<p>Adobe \u00e8 certificata in conformit\u00e0 con il Privacy Shield UE-USA. Il Privacy Shield \u00e8 un accordo tra gli Stati Uniti d'America e l'Unione Europea volto a garantire la conformit\u00e0 agli standard europei di protezione dei dati. Ulteriori informazioni sono disponibili all'indirizzo:\u00a0<a href=\"https:\/\/www.adobe.com\/de\/privacy\/eudatatransfers.html\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">https:\/\/www.adobe.com\/de\/privacy\/eudatatransfers.html<\/a>.<\/p>\n<p>I dati vengono memorizzati e analizzati sulla base dell'art. 6 par. 1 lett. f GDPR. Il gestore del sito web ha un interesse legittimo alla presentazione uniforme del carattere tipografico sul proprio sito web. Se \u00e8 stato richiesto un consenso corrispondente (ad es. consenso alla memorizzazione dei cookie), il trattamento avviene esclusivamente sulla base dell'art. 6 par. 1 lett. a GDPR; il consenso pu\u00f2 essere revocato in qualsiasi momento.<\/p>\n<p>Ulteriori informazioni sui font Adobe sono disponibili all'indirizzo:\u00a0<a href=\"https:\/\/www.adobe.com\/de\/privacy\/policies\/adobe-fonts.html\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">https:\/\/www.adobe.com\/de\/privacy\/policies\/adobe-fonts.html<\/a>.<\/p>\n<p>L'informativa sulla privacy di Adobe \u00e8 disponibile all'indirizzo:\u00a0<a href=\"https:\/\/www.adobe.com\/de\/privacy\/policy.html\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">https:\/\/www.adobe.com\/de\/privacy\/policy.html<\/a><\/p>\n<h3>Google Maps<\/h3>\n<p>Questo sito web utilizza il servizio di mappe Google Maps tramite un'API. Il fornitore \u00e8 Google Ireland Limited (\u201eGoogle\u201c), Gordon House, Barrow Street, Dublino 4, Irlanda.<\/p>\n<p>Per utilizzare le funzioni di Google Maps \u00e8 necessario salvare il vostro indirizzo IP. Queste informazioni vengono solitamente trasferite a un server di Google negli Stati Uniti e l\u00ec memorizzate. Il fornitore di questo sito non ha alcuna influenza su questo trasferimento di dati.<\/p>\n<p>L'utilizzo di Google Maps \u00e8 finalizzato a una presentazione accattivante delle nostre offerte online e a facilitare la ricerca dei luoghi da noi indicati sul sito web. Ci\u00f2 costituisce un interesse legittimo ai sensi dell'art. 6 comma 1 lett. f GDPR. Se \u00e8 stato richiesto un consenso corrispondente, il trattamento avviene esclusivamente sulla base dell'art. 6 par. 1 lett. a GDPR; il consenso pu\u00f2 essere revocato in qualsiasi momento.<\/p>\n<p>Per ulteriori informazioni sul trattamento dei dati degli utenti, consultare l'informativa sulla privacy di Google:\u00a0<a href=\"https:\/\/policies.google.com\/privacy?hl=de\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">https:\/\/policies.google.com\/privacy?hl=de<\/a>.<\/p>\n<h3>Google reCAPTCHA<\/h3>\n<p>Su questo sito web utilizziamo \u201eGoogle reCAPTCHA\u201c (di seguito \u201ereCAPTCHA\u201c). Il fornitore \u00e8 Google Ireland Limited (\u201eGoogle\u201c), Gordon House, Barrow Street, Dublino 4, Irlanda.<\/p>\n<p>Lo scopo di reCAPTCHA \u00e8 quello di verificare se i dati inseriti in questo sito web (ad esempio in un modulo di contatto) sono stati inseriti da un essere umano o da un programma automatico. A tal fine, reCAPTCHA analizza il comportamento del visitatore del sito web in base a diverse caratteristiche. L'analisi inizia automaticamente non appena il visitatore entra nel sito web. Per l'analisi, reCAPTCHA valuta diverse informazioni (ad esempio, l'indirizzo IP, il tempo trascorso sul sito web dal visitatore o i movimenti del mouse effettuati dall'utente). I dati raccolti durante l'analisi vengono trasmessi a Google.<\/p>\n<p>Le analisi di reCAPTCHA vengono eseguite completamente in background. I visitatori del sito web non vengono informati che \u00e8 in corso un'analisi.<\/p>\n<p>I dati vengono memorizzati e analizzati sulla base dell'art. 6 par. 1 lett. f GDPR. Il gestore del sito web ha un interesse legittimo a proteggere il proprio sito web da spionaggio automatico abusivo e SPAM. Se \u00e8 stato richiesto un consenso corrispondente (ad es. consenso alla memorizzazione dei cookie), il trattamento avviene esclusivamente sulla base dell'art. 6 par. 1 lett. a GDPR; il consenso pu\u00f2 essere revocato in qualsiasi momento.<\/p>\n<p>Per ulteriori informazioni su Google reCAPTCHA, consultare l'Informativa sulla privacy di Google e i Termini di servizio di Google ai seguenti link:\u00a0<a href=\"https:\/\/policies.google.com\/privacy?hl=de\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">https:\/\/policies.google.com\/privacy?hl=de<\/a>\u00a0e\u00a0<a href=\"https:\/\/policies.google.com\/terms?hl=de\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">https:\/\/policies.google.com\/terms?hl=de<\/a>.<\/p>\n<h2>8. Fornitori di servizi di eCommerce e di pagamento<\/h2>\n<h3>Trattamento dei dati (dati dei clienti e dei contratti)<\/h3>\n<p>Raccogliamo, elaboriamo e utilizziamo i dati personali solo nella misura in cui ci\u00f2 \u00e8 necessario per l'instaurazione, il contenuto o la modifica del rapporto giuridico (dati di inventario). Ci\u00f2 avviene sulla base dell'art. 6 comma 1 lett. b GDPR, che consente il trattamento dei dati per l'adempimento di un contratto o di misure precontrattuali. Raccogliamo, elaboriamo e utilizziamo i dati personali relativi all'utilizzo di questo sito web (dati di utilizzo) solo nella misura in cui ci\u00f2 \u00e8 necessario per consentire o addebitare all'utente l'utilizzo del servizio.<\/p>\n<p>I dati del cliente raccolti saranno cancellati dopo il completamento dell'ordine o la cessazione del rapporto commerciale. I periodi di conservazione previsti dalla legge rimangono inalterati.<\/p>\n<h3>Trasmissione dei dati al momento della stipula di un contratto per negozi online, rivenditori e spedizione di merci<\/h3>\n<p>Trasmettiamo i dati personali a terzi solo se ci\u00f2 \u00e8 necessario nell'ambito dell'elaborazione del contratto, ad esempio alle aziende incaricate della consegna della merce o all'istituto di credito incaricato dell'elaborazione del pagamento. Qualsiasi ulteriore trasmissione di dati non avverr\u00e0 o avverr\u00e0 solo se avete espressamente acconsentito alla trasmissione. I vostri dati non saranno trasmessi a terzi senza il vostro esplicito consenso, ad esempio per scopi pubblicitari.<\/p>\n<p>La base per il trattamento dei dati \u00e8 l'art. 6 comma 1 lett. b GDPR, che consente il trattamento dei dati per l'adempimento di un contratto o di misure precontrattuali.<\/p>\n<h3>Trasmissione dei dati alla conclusione di un contratto per servizi e contenuti digitali<\/h3>\n<p>Trasmettiamo i dati personali a terzi solo se ci\u00f2 \u00e8 necessario nel contesto dell'elaborazione del contratto, ad esempio all'istituto di credito responsabile dell'elaborazione dei pagamenti.<\/p>\n<p>L'ulteriore trasmissione dei dati non avverr\u00e0 o avverr\u00e0 solo se avete espressamente acconsentito alla trasmissione. I vostri dati non saranno trasmessi a terzi senza il vostro esplicito consenso, ad esempio per scopi pubblicitari.<\/p>\n<p>La base per il trattamento dei dati \u00e8 l'art. 6 comma 1 lett. b GDPR, che consente il trattamento dei dati per l'adempimento di un contratto o di misure precontrattuali.<\/p>\n<p>&nbsp;<\/p>\n<h3>Klarna<\/h3>\n<p>Su questo sito web offriamo, tra le altre cose, il pagamento con i servizi di Klarna. Il fornitore \u00e8 Klarna AB, Sveav\u00e4gen 46, 111 34 Stoccolma, Svezia (di seguito \u201eKlarna\u201c).<\/p>\n<p>Klarna offre diverse opzioni di pagamento (ad es. acquisto rateale). Se decidete di pagare con Klarna (soluzione di pagamento Klarna), Klarna raccoglier\u00e0 diversi dati personali. I dettagli in merito sono riportati nell'informativa sulla privacy di Klarna al seguente link:\u00a0<a href=\"https:\/\/www.klarna.com\/de\/datenschutz\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">https:\/\/www.klarna.com\/de\/datenschutz\/<\/a>.<\/p>\n<p>Klarna utilizza i cookie per ottimizzare l'utilizzo della soluzione di pagamento Klarna. L'ottimizzazione della soluzione di checkout costituisce un interesse legittimo ai sensi dell'art. 6 comma 1 lett. f GDPR. I cookie sono piccoli file di testo che vengono memorizzati sul vostro dispositivo finale e non causano alcun danno. Rimangono sul vostro dispositivo finch\u00e9 non li cancellate. I dettagli sull'uso dei cookie di Klarna sono disponibili al seguente link:\u00a0<a href=\"https:\/\/cdn.klarna.com\/1.0\/shared\/content\/policy\/cookie\/de_de\/checkout.pdf\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">https:\/\/cdn.klarna.com\/1.0\/shared\/content\/policy\/cookie\/de_de\/checkout.pdf<\/a>.<\/p>\n<p>La trasmissione dei vostri dati a Klarna si basa sull'art. 6 comma 1 lett. a GDPR (consenso) e sull'art. 6 comma 1 lett. b GDPR (trattamento per l'adempimento di un contratto). Avete la possibilit\u00e0 di revocare il vostro consenso al trattamento dei dati in qualsiasi momento. La revoca non pregiudica l'efficacia delle operazioni di trattamento dei dati effettuate in passato.<\/p>\n<h3>Bonifico bancario istantaneo<\/h3>\n<p>Su questo sito web offriamo, tra l'altro, il pagamento tramite \u201eSofort\u00fcberweisung\u201c. Il fornitore di questo servizio di pagamento \u00e8 Sofort GmbH, Theresienh\u00f6he 12, 80339 Monaco (di seguito \u201eSofort GmbH\u201c).<\/p>\n<p>Con l'aiuto della procedura \u201eSofort\u00fcberweisung\u201c, riceviamo una conferma di pagamento da Sofort GmbH in tempo reale e possiamo iniziare immediatamente ad adempiere ai nostri obblighi.<\/p>\n<p>Se avete scelto il metodo di pagamento \u201eSofort\u00fcberweisung\u201c, trasmettete a Sofort GmbH il PIN e un TAN valido, con il quale pu\u00f2 accedere al vostro conto bancario online. Dopo aver effettuato l'accesso, Sofort GmbH controlla automaticamente il saldo del vostro conto ed esegue il bonifico a nostro favore utilizzando il TAN da voi trasmesso. Successivamente ci invia immediatamente una conferma della transazione. Dopo l'accesso, vengono controllati automaticamente anche il fatturato, il limite di credito del fido e l'esistenza di altri conti e dei relativi saldi.<\/p>\n<p>Oltre al PIN e al TAN, vengono trasmessi a Sofort GmbH anche i dati di pagamento inseriti dall'utente e i suoi dati personali. I vostri dati personali comprendono il vostro nome e cognome, l'indirizzo, il\/i numero\/i di telefono, l'indirizzo e-mail, l'indirizzo IP e qualsiasi altro dato necessario per l'elaborazione del pagamento. La trasmissione di questi dati \u00e8 necessaria per stabilire con certezza la vostra identit\u00e0 e per prevenire tentativi di frode.<\/p>\n<p>La trasmissione dei vostri dati a Sofort GmbH si basa sull'art. 6 par. 1 lett. a GDPR (consenso) e sull'art. 6 par. 1 lett. b GDPR (trattamento per l'adempimento di un contratto). Avete la possibilit\u00e0 di revocare il vostro consenso al trattamento dei dati in qualsiasi momento. La revoca non pregiudica l'efficacia delle operazioni di trattamento dei dati effettuate in passato.<\/p>\n<p>Per informazioni dettagliate sul pagamento con Sofort\u00fcberweisung, consultare i seguenti link:\u00a0<a href=\"https:\/\/www.sofort.de\/datenschutz.html\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">https:\/\/www.sofort.de\/datenschutz.html<\/a>\u00a0e\u00a0<a href=\"https:\/\/www.klarna.com\/sofort\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">https:\/\/www.klarna.com\/sofort\/<\/a>.<\/p>\n<h3>Paydirekt<\/h3>\n<p>Su questo sito web offriamo, tra le altre cose, il pagamento tramite Paydirekt. Il fornitore di questo servizio di pagamento \u00e8 Paydirekt GmbH, Hamburger Allee 26-28, 60486 Francoforte sul Meno, Germania (di seguito \u201ePaydirekt\u201c).<\/p>\n<p>Quando si effettua un pagamento con Paydirekt, Paydirekt raccoglie vari dati della transazione e li trasmette alla banca presso la quale si \u00e8 registrati con Paydirekt. Oltre ai dati necessari per il pagamento, Paydirekt pu\u00f2 raccogliere altri dati, come l'indirizzo di consegna o i singoli articoli del carrello, come parte dell'elaborazione della transazione.<\/p>\n<p>Paydirekt autentica quindi la transazione utilizzando la procedura di autenticazione memorizzata a tal fine presso la banca. L'importo del pagamento viene quindi trasferito dal tuo conto al nostro conto. N\u00e9 noi n\u00e9 terzi abbiamo accesso ai dati del tuo conto.<\/p>\n<p>I vostri dati vengono trasmessi a Paydirekt sulla base dell'art. 6 comma 1 lett. a GDPR (consenso) e dell'art. 6 comma 1 lett. b GDPR (trattamento per l'adempimento di un contratto). Avete la possibilit\u00e0 di revocare il vostro consenso al trattamento dei dati in qualsiasi momento. La revoca non pregiudica l'efficacia delle operazioni di trattamento dei dati effettuate in passato.<\/p>\n<p>Per i dettagli sul pagamento con Paydirekt, consultare i termini e le condizioni e l'informativa sulla privacy di Paydirekt all'indirizzo:\u00a0<a href=\"https:\/\/www.paydirekt.de\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">https:\/\/www.paydirekt.de\/<\/a>.<\/p>\n<h3>Digistore24<\/h3>\n<p>Alcuni dei nostri prodotti, servizi e contenuti sono offerti da Digistore24 come rivenditore. Il fornitore e partner contrattuale \u00e8 Digistore24 GmbH, St.-Godehard-Stra\u00dfe 32 in 31139 Hildesheim. In qualit\u00e0 di responsabile del trattamento, Digistore24 GmbH stabilisce nella propria informativa sulla privacy quali dati Digistore24 memorizza ed elabora quando si accede a questo sito web. Ulteriori informazioni sono disponibili nell'informativa sulla privacy di Digistore24:\u00a0<a href=\"https:\/\/www.digistore24.com\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">https:\/\/www.digistore24.com\/<\/a>.<\/p>\n<h2>9. servizi propri<\/h2>\n<h3>Gestione dei dati dei richiedenti<\/h3>\n<p>Vi offriamo la possibilit\u00e0 di candidarvi (ad esempio tramite e-mail, posta o modulo di candidatura online). Di seguito vi informiamo sulla portata, lo scopo e l'utilizzo dei vostri dati personali raccolti nell'ambito del processo di candidatura. Vi assicuriamo che i vostri dati saranno raccolti, elaborati e utilizzati in conformit\u00e0 alla legge sulla protezione dei dati e a tutte le altre disposizioni di legge e che i vostri dati saranno trattati in modo strettamente confidenziale.<\/p>\n<p><strong>Ambito e finalit\u00e0 della raccolta dati<\/strong><\/p>\n<p>Se ci inviate una candidatura, tratteremo i vostri dati personali associati (ad es. dati di contatto e di comunicazione, documenti di candidatura, appunti presi durante i colloqui di lavoro, ecc.) nella misura in cui ci\u00f2 \u00e8 necessario per decidere l'instaurazione di un rapporto di lavoro. La base giuridica \u00e8 costituita dal \u00a7 26 BDSG-nuovo di diritto tedesco (avvio di un rapporto di lavoro), dall'art. 6 comma 1 lett. b GDPR (avvio di un contratto generale) e - se avete dato il vostro consenso - dall'art. 6 comma 1 lett. a GDPR. Il consenso pu\u00f2 essere revocato in qualsiasi momento. I vostri dati personali saranno trasmessi all'interno della nostra azienda solo alle persone coinvolte nell'elaborazione della vostra candidatura.<\/p>\n<p>In caso di esito positivo della candidatura, i dati da voi trasmessi saranno memorizzati nei nostri sistemi di elaborazione dati sulla base del \u00a7 26 BDSG-nuovo e dell'art. 6 par. 1 lett. b GDPR ai fini dell'attuazione del rapporto di lavoro.<\/p>\n<p><strong>Periodo di conservazione dei dati<\/strong><\/p>\n<p>Se non siamo in grado di farvi un'offerta di lavoro, se rifiutate un'offerta di lavoro o se ritirate la vostra candidatura, ci riserviamo il diritto di conservare i dati da voi trasmessi sulla base dei nostri legittimi interessi (art. 6 par. 1 lett. f GDPR) per un massimo di 6 mesi dalla fine del processo di candidatura (rifiuto o ritiro della candidatura). I dati saranno poi cancellati e i documenti fisici di candidatura distrutti. La conservazione serve in particolare come prova in caso di controversia legale. Se \u00e8 evidente che i dati saranno necessari dopo la scadenza del periodo di 6 mesi (ad esempio, a causa di una controversia legale imminente o in corso), i dati saranno cancellati solo quando lo scopo dell'ulteriore conservazione non sar\u00e0 pi\u00f9 valido.<\/p>\n<p>I dati possono essere conservati anche pi\u00f9 a lungo se avete dato il vostro consenso (art. 6 par. 1 lett. a GDPR) o se gli obblighi di conservazione previsti dalla legge ne impediscono la cancellazione.<\/p>\n<p><strong>Inclusione nel pool di candidati<\/strong><\/p>\n<p>Se non vi facciamo un'offerta di lavoro, potete avere l'opportunit\u00e0 di essere inclusi nel nostro gruppo di candidati. In caso di accettazione, tutti i documenti e i dettagli della vostra candidatura saranno trasferiti al pool di candidati, in modo che possiate essere contattati in caso di offerte di lavoro adeguate.<\/p>\n<p>L'inclusione nel pool di candidati si basa esclusivamente sul vostro consenso esplicito (art. 6 par. 1 lett. a GDPR). Il consenso \u00e8 volontario e non \u00e8 legato al processo di candidatura in corso.\u00a0<strong>L'interessato pu\u00f2 revocare il proprio consenso in qualsiasi momento.<\/strong>\u00a0In questo caso, i dati saranno irrevocabilmente cancellati dal pool di candidati, a condizione che non vi siano motivi legali per conservarli.<\/p>\n<p>I dati del pool di richiedenti saranno cancellati irrevocabilmente entro due anni dalla concessione del consenso.<\/p>\n<h3>La nostra presenza sui social media<\/h3>\n<h4>Trattamento dei dati da parte dei social network<\/h4>\n<p>Manteniamo profili accessibili pubblicamente sui social network. I singoli social network che utilizziamo sono elencati di seguito.<\/p>\n<p>I social network come Facebook, Twitter ecc. possono generalmente analizzare in modo completo il comportamento dell'utente quando visita il loro sito web o un sito web con contenuti integrati nei social media (ad es. pulsanti \"like\" o banner pubblicitari). La visita alle nostre presenze sui social media d\u00e0 luogo a numerose operazioni di trattamento dei dati rilevanti ai fini della protezione dei dati. In dettaglio:<\/p>\n<p>Se siete connessi al vostro account di social media e visitate la nostra presenza sui social media, il gestore del portale di social media pu\u00f2 assegnare questa visita al vostro account utente. Tuttavia, i vostri dati personali possono essere raccolti anche se non avete effettuato l'accesso o non disponete di un account presso il rispettivo portale di social media. In questo caso, la raccolta dei dati avviene, ad esempio, tramite cookie memorizzati sul vostro dispositivo finale o tramite la registrazione del vostro indirizzo IP.<\/p>\n<p>Con l'aiuto dei dati cos\u00ec raccolti, i gestori dei portali di social media possono creare profili utente in cui vengono memorizzati le preferenze e gli interessi dell'utente. In questo modo, la pubblicit\u00e0 basata sugli interessi pu\u00f2 essere visualizzata all'interno e all'esterno della rispettiva presenza sui social media. Se l'utente dispone di un account presso il rispettivo social network, la pubblicit\u00e0 basata sugli interessi pu\u00f2 essere visualizzata su tutti i dispositivi sui quali l'utente ha effettuato o ha effettuato l'accesso.<\/p>\n<p>Si noti inoltre che non possiamo tenere traccia di tutte le operazioni di trattamento sui portali di social media. A seconda del fornitore, ulteriori operazioni di elaborazione possono quindi essere eseguite dai gestori dei portali di social media. Per maggiori dettagli, si prega di consultare le condizioni d'uso e le disposizioni sulla protezione dei dati dei rispettivi portali di social media.<\/p>\n<p><strong>Base giuridica<\/strong><\/p>\n<p>La nostra presenza sui social media ha lo scopo di garantire la pi\u00f9 ampia presenza possibile su Internet. Si tratta di un interesse legittimo ai sensi dell'art. 6 par. 1 lett. f GDPR. I processi di analisi avviati dai social network possono basarsi su diverse basi giuridiche, che devono essere specificate dai gestori dei social network (ad es. consenso ai sensi dell'art. 6 par. 1 lett. a GDPR).<\/p>\n<p><strong>Parte responsabile e rivendicazione dei diritti<\/strong><\/p>\n<p>Se visitate uno dei nostri siti di social media (ad es. Facebook), siamo congiuntamente responsabili con il gestore della piattaforma di social media per le operazioni di trattamento dei dati attivate durante questa visita. Potete far valere i vostri diritti (informazione, rettifica, cancellazione, limitazione del trattamento, portabilit\u00e0 dei dati e reclamo) sia nei nostri confronti che nei confronti del gestore del rispettivo portale di social media (ad esempio, nei confronti di Facebook).<\/p>\n<p>Si prega di notare che, nonostante la nostra responsabilit\u00e0 congiunta con gli operatori dei portali di social media, non abbiamo il pieno controllo sulle operazioni di elaborazione dei dati dei portali di social media. Le nostre opzioni sono in gran parte determinate dalla politica aziendale del rispettivo fornitore.<\/p>\n<p><strong>Durata della conservazione<\/strong><\/p>\n<p>I dati raccolti direttamente da noi tramite la presenza sui social media saranno cancellati dai nostri sistemi non appena lo scopo della loro memorizzazione non sar\u00e0 pi\u00f9 valido, l'utente ci chieder\u00e0 di cancellarli, revocher\u00e0 il suo consenso alla memorizzazione o lo scopo della memorizzazione dei dati non sar\u00e0 pi\u00f9 valido. I cookie memorizzati rimangono sul vostro dispositivo finale fino a quando non li cancellate. Le disposizioni di legge obbligatorie, in particolare i periodi di conservazione, rimangono inalterate.<\/p>\n<p>Non abbiamo alcuna influenza sul periodo di conservazione dei vostri dati che vengono memorizzati dagli operatori dei social network per i loro scopi. Per maggiori dettagli, si prega di contattare direttamente i gestori dei social network (ad esempio, nella loro politica sulla privacy, vedi sotto).<\/p>\n<h4>I social network in dettaglio<\/h4>\n<p><strong>Facebook<\/strong><\/p>\n<p>Abbiamo un profilo su Facebook. Il fornitore di questo servizio \u00e8 Facebook Ireland Limited, 4 Grand Canal Square, Dublino 2, Irlanda. Secondo Facebook, i dati raccolti vengono trasferiti anche negli Stati Uniti e in altri Paesi terzi.<\/p>\n<p>Abbiamo stipulato un accordo con Facebook sul trattamento congiunto dei dati (Controller Addendum). Questo accordo specifica per quali operazioni di trattamento dei dati siamo responsabili noi o Facebook quando visitate la nostra pagina Facebook. Potete consultare questo accordo al seguente link:\u00a0<a href=\"https:\/\/www.facebook.com\/legal\/terms\/page_controller_addendum\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">https:\/\/www.facebook.com\/legal\/terms\/page_controller_addendum<\/a>.<\/p>\n<p><strong>\u00c8 possibile personalizzare le impostazioni pubblicitarie nel proprio account utente. Per farlo, cliccate sul seguente link e accedete:<\/strong>\u00a0<a href=\"https:\/\/www.facebook.com\/settings?tab=ads\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">https:\/\/www.facebook.com\/settings?tab=ads<\/a>.<\/p>\n<p>I dettagli sono disponibili nell'informativa sulla privacy di Facebook:\u00a0<a href=\"https:\/\/www.facebook.com\/about\/privacy\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">https:\/\/www.facebook.com\/about\/privacy\/<\/a>.<\/p>\n<p><strong>Instagram<\/strong><\/p>\n<p>Abbiamo un profilo su Instagram. Il provider \u00e8 Instagram Inc, 1601 Willow Road, Menlo Park, CA, 94025, USA. I dettagli sul trattamento dei dati personali sono riportati nell'informativa sulla privacy di Instagram:\u00a0<a href=\"https:\/\/help.instagram.com\/519522125107875\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">https:\/\/help.instagram.com\/519522125107875<\/a>.<\/p>\n<p><strong>Pinterest<\/strong><\/p>\n<p>Abbiamo un profilo su Pinterest. Il gestore \u00e8 Pinterest Inc, 808 Brannan Street San Francisco, CA 94103-490, USA (\u201ePinterest\u201c). I dettagli sul trattamento dei vostri dati personali sono riportati nell'informativa sulla privacy di Pinterest:\u00a0<a href=\"https:\/\/policy.pinterest.com\/de\/privacy-policy\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">https:\/\/policy.pinterest.com\/de\/privacy-policy<\/a>.<\/p>\n<p>alphora.de 2020 |\u00a0<a href=\"https:\/\/www.alphora.de\/impressum\/\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">Impronta<\/a>\u00a0<a href=\"https:\/\/www.alphora.de\/datenschutzerklaerung\/\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">Protezione dei dati<\/a>\u00a0<a href=\"https:\/\/www.alphora.de\/cookie-einstellungen\/\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">Impostazioni dei cookie<\/a><\/p>\n<\/section>\n<div id=\"simple-translate\">\n<div>\n<div class=\"simple-translate-button isShow\" style=\"height: 22px; width: 22px; top: 2479px; left: 450px;\"><\/div>\n<div class=\"simple-translate-panel\" style=\"width: 300px; height: 200px; top: 0px; left: 0px; font-size: 13px; background-color: #ffffff;\">\n<div class=\"simple-translate-result-wrapper\" style=\"overflow: hidden;\">\n<div class=\"simple-translate-move\"><\/div>\n<div class=\"simple-translate-result-contents\">\n<p class=\"simple-translate-candidate\" style=\"color: #737373;\">\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"notranslate\"><\/div>","protected":false},"excerpt":{"rendered":"<p>1. La protezione dei dati in sintesi Informazioni generali Le seguenti informazioni forniscono una semplice panoramica di ci\u00f2 che accade ai vostri dati personali quando visitate questo sito web. Per dati personali si intendono tutti i dati che possono essere utilizzati per identificarvi personalmente. Informazioni dettagliate sul tema della protezione dei dati sono disponibili nella nostra politica sulla privacy elencata sotto questo testo. <\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2867","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Datenschutz-Bestimmungen - Win &amp; Office WS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/winandofficews.com\/it\/datenschutzerklaerung\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Datenschutz-Bestimmungen - Win &amp; Office WS\" \/>\n<meta property=\"og:description\" content=\"1. Datenschutz auf einen Blick Allgemeine Hinweise Die folgenden Hinweise geben einen einfachen \u00dcberblick dar\u00fcber, was mit Ihren personenbezogenen Daten passiert, wenn Sie diese Website besuchen. Personenbezogene Daten sind alle Daten, mit denen Sie pers\u00f6nlich identifiziert werden k\u00f6nnen. Ausf\u00fchrliche Informationen zum Thema Datenschutz entnehmen Sie unserer unter diesem Text aufgef\u00fchrten&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/winandofficews.com\/it\/datenschutzerklaerung\/\" \/>\n<meta property=\"og:site_name\" content=\"Win &amp; Office WS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/winandofficews\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-25T18:36:01+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@WINDOWSANDOFFI1\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"21 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/winandofficews.com\\\/datenschutzerklaerung\\\/\",\"url\":\"https:\\\/\\\/winandofficews.com\\\/datenschutzerklaerung\\\/\",\"name\":\"Datenschutz-Bestimmungen - Win &amp; Office WS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/winandofficews.com\\\/#website\"},\"datePublished\":\"2020-07-25T23:33:33+00:00\",\"dateModified\":\"2025-08-25T18:36:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/winandofficews.com\\\/datenschutzerklaerung\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/winandofficews.com\\\/datenschutzerklaerung\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/winandofficews.com\\\/datenschutzerklaerung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/winandofficews.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Privacy Policy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/winandofficews.com\\\/#website\",\"url\":\"https:\\\/\\\/winandofficews.com\\\/\",\"name\":\"Win & Office WS\",\"description\":\"Wholesales Store of Office\",\"publisher\":{\"@id\":\"https:\\\/\\\/winandofficews.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/winandofficews.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/winandofficews.com\\\/#organization\",\"name\":\"Win & Office WS\",\"url\":\"https:\\\/\\\/winandofficews.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/winandofficews.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/winandofficews.com\\\/wp-content\\\/uploads\\\/logo14.png\",\"contentUrl\":\"https:\\\/\\\/winandofficews.com\\\/wp-content\\\/uploads\\\/logo14.png\",\"width\":322,\"height\":116,\"caption\":\"Win & Office WS\"},\"image\":{\"@id\":\"https:\\\/\\\/winandofficews.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/winandofficews\\\/\",\"https:\\\/\\\/x.com\\\/WINDOWSANDOFFI1\",\"https:\\\/\\\/www.instagram.com\\\/winandoffice.ws\\\/\",\"https:\\\/\\\/de.pinterest.com\\\/winandofficews_official\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@winandofficews\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCPI87ZZIvl272mOtG5sL8Cg\",\"https:\\\/\\\/de.trustpilot.com\\\/review\\\/winandofficews.com\",\"https:\\\/\\\/www.trustami.com\\\/review\\\/win-and-office-wholesales-rating\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Informativa sulla privacy - Win &amp; Office WS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/winandofficews.com\/it\/datenschutzerklaerung\/","og_locale":"it_IT","og_type":"article","og_title":"Datenschutz-Bestimmungen - Win &amp; Office WS","og_description":"1. Datenschutz auf einen Blick Allgemeine Hinweise Die folgenden Hinweise geben einen einfachen \u00dcberblick dar\u00fcber, was mit Ihren personenbezogenen Daten passiert, wenn Sie diese Website besuchen. Personenbezogene Daten sind alle Daten, mit denen Sie pers\u00f6nlich identifiziert werden k\u00f6nnen. Ausf\u00fchrliche Informationen zum Thema Datenschutz entnehmen Sie unserer unter diesem Text aufgef\u00fchrten&hellip;","og_url":"https:\/\/winandofficews.com\/it\/datenschutzerklaerung\/","og_site_name":"Win &amp; Office WS","article_publisher":"https:\/\/www.facebook.com\/winandofficews\/","article_modified_time":"2025-08-25T18:36:01+00:00","twitter_card":"summary_large_image","twitter_site":"@WINDOWSANDOFFI1","twitter_misc":{"Tempo di lettura stimato":"21 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/winandofficews.com\/datenschutzerklaerung\/","url":"https:\/\/winandofficews.com\/datenschutzerklaerung\/","name":"Informativa sulla privacy - Win &amp; Office WS","isPartOf":{"@id":"https:\/\/winandofficews.com\/#website"},"datePublished":"2020-07-25T23:33:33+00:00","dateModified":"2025-08-25T18:36:01+00:00","breadcrumb":{"@id":"https:\/\/winandofficews.com\/datenschutzerklaerung\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/winandofficews.com\/datenschutzerklaerung\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/winandofficews.com\/datenschutzerklaerung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/winandofficews.com\/"},{"@type":"ListItem","position":2,"name":"Privacy Policy"}]},{"@type":"WebSite","@id":"https:\/\/winandofficews.com\/#website","url":"https:\/\/winandofficews.com\/","name":"Win e Office WS","description":"Negozio all'ingrosso di Office","publisher":{"@id":"https:\/\/winandofficews.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/winandofficews.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/winandofficews.com\/#organization","name":"Win e Office WS","url":"https:\/\/winandofficews.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/winandofficews.com\/#\/schema\/logo\/image\/","url":"https:\/\/winandofficews.com\/wp-content\/uploads\/logo14.png","contentUrl":"https:\/\/winandofficews.com\/wp-content\/uploads\/logo14.png","width":322,"height":116,"caption":"Win & Office WS"},"image":{"@id":"https:\/\/winandofficews.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/winandofficews\/","https:\/\/x.com\/WINDOWSANDOFFI1","https:\/\/www.instagram.com\/winandoffice.ws\/","https:\/\/de.pinterest.com\/winandofficews_official\/","https:\/\/www.tiktok.com\/@winandofficews","https:\/\/www.youtube.com\/channel\/UCPI87ZZIvl272mOtG5sL8Cg","https:\/\/de.trustpilot.com\/review\/winandofficews.com","https:\/\/www.trustami.com\/review\/win-and-office-wholesales-rating"]}]}},"_links":{"self":[{"href":"https:\/\/winandofficews.com\/it\/wp-json\/wp\/v2\/pages\/2867","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/winandofficews.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/winandofficews.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/winandofficews.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/winandofficews.com\/it\/wp-json\/wp\/v2\/comments?post=2867"}],"version-history":[{"count":0,"href":"https:\/\/winandofficews.com\/it\/wp-json\/wp\/v2\/pages\/2867\/revisions"}],"wp:attachment":[{"href":"https:\/\/winandofficews.com\/it\/wp-json\/wp\/v2\/media?parent=2867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}